{"id":25,"count":2,"description":"","link":"https:\/\/dev.mushroomcreative.com\/mushroom\/category\/gigs\/","name":"Gigs","slug":"gigs","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.mushroomcreative.com\/mushroom\/wp-json\/wp\/v2\/categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.mushroomcreative.com\/mushroom\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dev.mushroomcreative.com\/mushroom\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dev.mushroomcreative.com\/mushroom\/wp-json\/wp\/v2\/posts?categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}